{"id":50159,"date":"2021-01-27T15:15:19","date_gmt":"2021-01-28T15:16:10","guid":{"rendered":"https:\/\/labs.giamaica.app\/webit\/adriabandiere.com\/shop\/uncategorized\/number-1-ci\/"},"modified":"2021-01-28T16:16:10","modified_gmt":"2021-01-28T15:16:10","slug":"number-1-ci","status":"publish","type":"product","link":"https:\/\/www.adriabandiere.com\/en\/prodotti\/flags\/signalling-nautical-flags\/number-1-ci\/","title":{"rendered":"NUMBER 1 CI"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Number 1 there, 20&#215;30 cm<br \/>\n17b02-01 Number 1 ci, 30&#215;45 cm<br \/>\n17b03-01 Number 1 ci, 40&#215;60 cm<br \/>\n17b04-01 Number 1 ci, 50&#215;70 cm<br \/>\n17b05-01 Number 1 ci, 60&#215;73 cm<br \/>\n17b06-01 Number 1 ci, 80&#215;98 cm<br \/>\n17b07-01 Number 1 ci, 80&#215;120 cm<br \/>\n17b08-01 Number 1 ci, 100&#215;150 cm<br \/>\n17b09-01 Number 1 ci, 120&#215;160 cm<br \/>\n17b10-01 Number 1 ci, 140&#215;170 cm<\/p>\n","protected":false},"featured_media":44005,"template":"","meta":{"_acf_changed":false,"ngg_post_thumbnail":0},"product_brand":[],"product_cat":[454,493],"product_tag":[],"class_list":{"0":"post-50159","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-flags","7":"product_cat-signalling-nautical-flags","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.11 (Yoast SEO v20.11) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>NUMBER 1 CI - AdriaBandiere<\/title>\n<meta name=\"description\" content=\"Scopri NUMBER 1 CI e gli altri prodotti del catalogo di AdriaBandiere. Entra nel sito.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.adriabandiere.com\/en\/prodotti\/flags\/signalling-nautical-flags\/number-1-ci\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NUMBER 1 CI\" \/>\n<meta property=\"og:description\" content=\"Scopri NUMBER 1 CI e gli altri prodotti del catalogo di AdriaBandiere. Entra nel sito.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.adriabandiere.com\/en\/prodotti\/flags\/signalling-nautical-flags\/number-1-ci\/\" \/>\n<meta property=\"og:site_name\" content=\"Adria Bandiere\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.adriabandiere.com\/wp-content\/uploads\/2021\/01\/17b01-01-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"429\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.adriabandiere.com\/en\/prodotti\/flags\/signalling-nautical-flags\/number-1-ci\/\",\"url\":\"https:\/\/www.adriabandiere.com\/en\/prodotti\/flags\/signalling-nautical-flags\/number-1-ci\/\",\"name\":\"NUMBER 1 CI - AdriaBandiere\",\"isPartOf\":{\"@id\":\"https:\/\/www.adriabandiere.com\/en\/#website\"},\"datePublished\":\"2021-01-28T15:16:10+00:00\",\"dateModified\":\"2021-01-28T15:16:10+00:00\",\"description\":\"Scopri NUMBER 1 CI e gli altri prodotti del catalogo di AdriaBandiere. Entra nel sito.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.adriabandiere.com\/en\/prodotti\/flags\/signalling-nautical-flags\/number-1-ci\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.adriabandiere.com\/en\/prodotti\/flags\/signalling-nautical-flags\/number-1-ci\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.adriabandiere.com\/en\/prodotti\/flags\/signalling-nautical-flags\/number-1-ci\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prodotti\",\"item\":\"https:\/\/www.adriabandiere.com\/it\/prodotti\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NUMBER 1 CI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.adriabandiere.com\/en\/#website\",\"url\":\"https:\/\/www.adriabandiere.com\/en\/\",\"name\":\"Adria Bandiere\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.adriabandiere.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"NUMBER 1 CI - AdriaBandiere","description":"Scopri NUMBER 1 CI e gli altri prodotti del catalogo di AdriaBandiere. Entra nel sito.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.adriabandiere.com\/en\/prodotti\/flags\/signalling-nautical-flags\/number-1-ci\/","og_locale":"en_US","og_type":"article","og_title":"NUMBER 1 CI","og_description":"Scopri NUMBER 1 CI e gli altri prodotti del catalogo di AdriaBandiere. Entra nel sito.","og_url":"https:\/\/www.adriabandiere.com\/en\/prodotti\/flags\/signalling-nautical-flags\/number-1-ci\/","og_site_name":"Adria Bandiere","og_image":[{"width":1024,"height":429,"url":"https:\/\/www.adriabandiere.com\/wp-content\/uploads\/2021\/01\/17b01-01-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.adriabandiere.com\/en\/prodotti\/flags\/signalling-nautical-flags\/number-1-ci\/","url":"https:\/\/www.adriabandiere.com\/en\/prodotti\/flags\/signalling-nautical-flags\/number-1-ci\/","name":"NUMBER 1 CI - AdriaBandiere","isPartOf":{"@id":"https:\/\/www.adriabandiere.com\/en\/#website"},"datePublished":"2021-01-28T15:16:10+00:00","dateModified":"2021-01-28T15:16:10+00:00","description":"Scopri NUMBER 1 CI e gli altri prodotti del catalogo di AdriaBandiere. Entra nel sito.","breadcrumb":{"@id":"https:\/\/www.adriabandiere.com\/en\/prodotti\/flags\/signalling-nautical-flags\/number-1-ci\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.adriabandiere.com\/en\/prodotti\/flags\/signalling-nautical-flags\/number-1-ci\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.adriabandiere.com\/en\/prodotti\/flags\/signalling-nautical-flags\/number-1-ci\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prodotti","item":"https:\/\/www.adriabandiere.com\/it\/prodotti\/"},{"@type":"ListItem","position":2,"name":"NUMBER 1 CI"}]},{"@type":"WebSite","@id":"https:\/\/www.adriabandiere.com\/en\/#website","url":"https:\/\/www.adriabandiere.com\/en\/","name":"Adria Bandiere","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.adriabandiere.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.adriabandiere.com\/en\/wp-json\/wp\/v2\/product\/50159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.adriabandiere.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.adriabandiere.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.adriabandiere.com\/en\/wp-json\/wp\/v2\/media\/44005"}],"wp:attachment":[{"href":"https:\/\/www.adriabandiere.com\/en\/wp-json\/wp\/v2\/media?parent=50159"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.adriabandiere.com\/en\/wp-json\/wp\/v2\/product_brand?post=50159"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.adriabandiere.com\/en\/wp-json\/wp\/v2\/product_cat?post=50159"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.adriabandiere.com\/en\/wp-json\/wp\/v2\/product_tag?post=50159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}