{"id":49291,"date":"2021-01-27T15:12:36","date_gmt":"2021-01-28T15:07:02","guid":{"rendered":"https:\/\/labs.giamaica.app\/webit\/adriabandiere.com\/shop\/uncategorized\/papua-new-military-guinea\/"},"modified":"2021-01-28T16:07:02","modified_gmt":"2021-01-28T15:07:02","slug":"papua-new-guinea-military","status":"publish","type":"product","link":"https:\/\/www.adriabandiere.com\/en\/prodotti\/flags\/foreign-nations\/papua-new-guinea-military\/","title":{"rendered":"PAPUA NEW MILITARY GUINEA"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Papua new guinea military, 20&#215;30 cm<br \/>\nbp352 Papua new guinea military, 30&#215;45 cm<br \/>\nbp353 Papua new guinea military, 40&#215;60 cm<br \/>\nbp354 Papua new guinea military, 50&#215;75 cm<br \/>\nbp355 Papua new guinea military, 70&#215;100 cm<br \/>\nbp356 Papua new guinea military, 80&#215;120 cm<br \/>\nbp357 Papua new guinea military, 100&#215;150 cm<br \/>\nbp358 Papua new guinea military, 130&#215;200 cm<br \/>\nbp359 Papua new guinea military, 150&#215;225 cm<br \/>\nbp360 Papua new guinea military, 200&#215;300 cm<\/p>\n","protected":false},"featured_media":43095,"template":"","meta":{"_acf_changed":false,"ngg_post_thumbnail":0},"product_brand":[],"product_cat":[454,481],"product_tag":[],"class_list":{"0":"post-49291","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-flags","7":"product_cat-foreign-nations","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.11 (Yoast SEO v20.11) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PAPUA NEW MILITARY GUINEA - AdriaBandiere<\/title>\n<meta name=\"description\" content=\"Scopri PAPUA NEW MILITARY GUINEA e gli altri prodotti del catalogo di AdriaBandiere. Entra nel sito.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.adriabandiere.com\/en\/prodotti\/flags\/foreign-nations\/papua-new-guinea-military\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PAPUA NEW MILITARY GUINEA\" \/>\n<meta property=\"og:description\" content=\"Scopri PAPUA NEW MILITARY GUINEA e gli altri prodotti del catalogo di AdriaBandiere. Entra nel sito.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.adriabandiere.com\/en\/prodotti\/flags\/foreign-nations\/papua-new-guinea-military\/\" \/>\n<meta property=\"og:site_name\" content=\"Adria Bandiere\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.adriabandiere.com\/wp-content\/uploads\/2021\/01\/bp351-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.adriabandiere.com\/en\/prodotti\/flags\/foreign-nations\/papua-new-guinea-military\/\",\"url\":\"https:\/\/www.adriabandiere.com\/en\/prodotti\/flags\/foreign-nations\/papua-new-guinea-military\/\",\"name\":\"PAPUA NEW MILITARY GUINEA - AdriaBandiere\",\"isPartOf\":{\"@id\":\"https:\/\/www.adriabandiere.com\/en\/#website\"},\"datePublished\":\"2021-01-28T15:07:02+00:00\",\"dateModified\":\"2021-01-28T15:07:02+00:00\",\"description\":\"Scopri PAPUA NEW MILITARY GUINEA e gli altri prodotti del catalogo di AdriaBandiere. Entra nel sito.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.adriabandiere.com\/en\/prodotti\/flags\/foreign-nations\/papua-new-guinea-military\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.adriabandiere.com\/en\/prodotti\/flags\/foreign-nations\/papua-new-guinea-military\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.adriabandiere.com\/en\/prodotti\/flags\/foreign-nations\/papua-new-guinea-military\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prodotti\",\"item\":\"https:\/\/www.adriabandiere.com\/it\/prodotti\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PAPUA NEW MILITARY GUINEA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.adriabandiere.com\/en\/#website\",\"url\":\"https:\/\/www.adriabandiere.com\/en\/\",\"name\":\"Adria Bandiere\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.adriabandiere.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"PAPUA NEW MILITARY GUINEA - AdriaBandiere","description":"Scopri PAPUA NEW MILITARY GUINEA e gli altri prodotti del catalogo di AdriaBandiere. Entra nel sito.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.adriabandiere.com\/en\/prodotti\/flags\/foreign-nations\/papua-new-guinea-military\/","og_locale":"en_US","og_type":"article","og_title":"PAPUA NEW MILITARY GUINEA","og_description":"Scopri PAPUA NEW MILITARY GUINEA e gli altri prodotti del catalogo di AdriaBandiere. Entra nel sito.","og_url":"https:\/\/www.adriabandiere.com\/en\/prodotti\/flags\/foreign-nations\/papua-new-guinea-military\/","og_site_name":"Adria Bandiere","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.adriabandiere.com\/wp-content\/uploads\/2021\/01\/bp351-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.adriabandiere.com\/en\/prodotti\/flags\/foreign-nations\/papua-new-guinea-military\/","url":"https:\/\/www.adriabandiere.com\/en\/prodotti\/flags\/foreign-nations\/papua-new-guinea-military\/","name":"PAPUA NEW MILITARY GUINEA - AdriaBandiere","isPartOf":{"@id":"https:\/\/www.adriabandiere.com\/en\/#website"},"datePublished":"2021-01-28T15:07:02+00:00","dateModified":"2021-01-28T15:07:02+00:00","description":"Scopri PAPUA NEW MILITARY GUINEA e gli altri prodotti del catalogo di AdriaBandiere. Entra nel sito.","breadcrumb":{"@id":"https:\/\/www.adriabandiere.com\/en\/prodotti\/flags\/foreign-nations\/papua-new-guinea-military\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.adriabandiere.com\/en\/prodotti\/flags\/foreign-nations\/papua-new-guinea-military\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.adriabandiere.com\/en\/prodotti\/flags\/foreign-nations\/papua-new-guinea-military\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prodotti","item":"https:\/\/www.adriabandiere.com\/it\/prodotti\/"},{"@type":"ListItem","position":2,"name":"PAPUA NEW MILITARY GUINEA"}]},{"@type":"WebSite","@id":"https:\/\/www.adriabandiere.com\/en\/#website","url":"https:\/\/www.adriabandiere.com\/en\/","name":"Adria Bandiere","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.adriabandiere.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.adriabandiere.com\/en\/wp-json\/wp\/v2\/product\/49291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.adriabandiere.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.adriabandiere.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.adriabandiere.com\/en\/wp-json\/wp\/v2\/media\/43095"}],"wp:attachment":[{"href":"https:\/\/www.adriabandiere.com\/en\/wp-json\/wp\/v2\/media?parent=49291"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.adriabandiere.com\/en\/wp-json\/wp\/v2\/product_brand?post=49291"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.adriabandiere.com\/en\/wp-json\/wp\/v2\/product_cat?post=49291"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.adriabandiere.com\/en\/wp-json\/wp\/v2\/product_tag?post=49291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}