{"id":49985,"date":"2021-01-27T15:14:55","date_gmt":"2021-01-28T15:14:46","guid":{"rendered":"https:\/\/labs.giamaica.app\/webit\/adriabandiere.com\/shop\/unkategorisiert\/s-regatta-flag\/"},"modified":"2021-01-28T16:14:46","modified_gmt":"2021-01-28T15:14:46","slug":"flaggenregatta-s","status":"publish","type":"product","link":"https:\/\/www.adriabandiere.com\/de\/prodotti\/flaggen\/nautische-signalflaggen\/flaggenregatta-s\/","title":{"rendered":"S REGATTA FLAG"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>S, cm 40&#215;60 roter und wei\u00dfer Hintergrund f\u00fcr Regattasignalisierung<\/p>\n","protected":false},"featured_media":54077,"template":"","meta":{"_acf_changed":false,"ngg_post_thumbnail":0},"product_brand":[],"product_cat":[456,491],"product_tag":[],"class_list":{"0":"post-49985","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-flaggen","7":"product_cat-nautische-signalflaggen","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.11 (Yoast SEO v20.11) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>S REGATTA FLAG - AdriaBandiere<\/title>\n<meta name=\"description\" content=\"Scopri S REGATTA FLAG e gli altri prodotti del catalogo di AdriaBandiere. Entra nel sito.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.adriabandiere.com\/de\/prodotti\/flaggen\/nautische-signalflaggen\/flaggenregatta-s\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S REGATTA FLAG\" \/>\n<meta property=\"og:description\" content=\"Scopri S REGATTA FLAG e gli altri prodotti del catalogo di AdriaBandiere. Entra nel sito.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.adriabandiere.com\/de\/prodotti\/flaggen\/nautische-signalflaggen\/flaggenregatta-s\/\" \/>\n<meta property=\"og:site_name\" content=\"Adria Bandiere\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.adriabandiere.com\/wp-content\/uploads\/2021\/01\/regata-s.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"425\" \/>\n\t<meta property=\"og:image:height\" content=\"284\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.adriabandiere.com\/de\/prodotti\/flaggen\/nautische-signalflaggen\/flaggenregatta-s\/\",\"url\":\"https:\/\/www.adriabandiere.com\/de\/prodotti\/flaggen\/nautische-signalflaggen\/flaggenregatta-s\/\",\"name\":\"S REGATTA FLAG - AdriaBandiere\",\"isPartOf\":{\"@id\":\"https:\/\/www.adriabandiere.com\/de\/#website\"},\"datePublished\":\"2021-01-28T15:14:46+00:00\",\"dateModified\":\"2021-01-28T15:14:46+00:00\",\"description\":\"Scopri S REGATTA FLAG e gli altri prodotti del catalogo di AdriaBandiere. Entra nel sito.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.adriabandiere.com\/de\/prodotti\/flaggen\/nautische-signalflaggen\/flaggenregatta-s\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.adriabandiere.com\/de\/prodotti\/flaggen\/nautische-signalflaggen\/flaggenregatta-s\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.adriabandiere.com\/de\/prodotti\/flaggen\/nautische-signalflaggen\/flaggenregatta-s\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prodotti\",\"item\":\"https:\/\/www.adriabandiere.com\/it\/prodotti\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S REGATTA FLAG\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.adriabandiere.com\/de\/#website\",\"url\":\"https:\/\/www.adriabandiere.com\/de\/\",\"name\":\"Adria Bandiere\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.adriabandiere.com\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"S REGATTA FLAG - AdriaBandiere","description":"Scopri S REGATTA FLAG e gli altri prodotti del catalogo di AdriaBandiere. Entra nel sito.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.adriabandiere.com\/de\/prodotti\/flaggen\/nautische-signalflaggen\/flaggenregatta-s\/","og_locale":"de_DE","og_type":"article","og_title":"S REGATTA FLAG","og_description":"Scopri S REGATTA FLAG e gli altri prodotti del catalogo di AdriaBandiere. Entra nel sito.","og_url":"https:\/\/www.adriabandiere.com\/de\/prodotti\/flaggen\/nautische-signalflaggen\/flaggenregatta-s\/","og_site_name":"Adria Bandiere","og_image":[{"width":425,"height":284,"url":"https:\/\/www.adriabandiere.com\/wp-content\/uploads\/2021\/01\/regata-s.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.adriabandiere.com\/de\/prodotti\/flaggen\/nautische-signalflaggen\/flaggenregatta-s\/","url":"https:\/\/www.adriabandiere.com\/de\/prodotti\/flaggen\/nautische-signalflaggen\/flaggenregatta-s\/","name":"S REGATTA FLAG - AdriaBandiere","isPartOf":{"@id":"https:\/\/www.adriabandiere.com\/de\/#website"},"datePublished":"2021-01-28T15:14:46+00:00","dateModified":"2021-01-28T15:14:46+00:00","description":"Scopri S REGATTA FLAG e gli altri prodotti del catalogo di AdriaBandiere. Entra nel sito.","breadcrumb":{"@id":"https:\/\/www.adriabandiere.com\/de\/prodotti\/flaggen\/nautische-signalflaggen\/flaggenregatta-s\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.adriabandiere.com\/de\/prodotti\/flaggen\/nautische-signalflaggen\/flaggenregatta-s\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.adriabandiere.com\/de\/prodotti\/flaggen\/nautische-signalflaggen\/flaggenregatta-s\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prodotti","item":"https:\/\/www.adriabandiere.com\/it\/prodotti\/"},{"@type":"ListItem","position":2,"name":"S REGATTA FLAG"}]},{"@type":"WebSite","@id":"https:\/\/www.adriabandiere.com\/de\/#website","url":"https:\/\/www.adriabandiere.com\/de\/","name":"Adria Bandiere","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.adriabandiere.com\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.adriabandiere.com\/de\/wp-json\/wp\/v2\/product\/49985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.adriabandiere.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.adriabandiere.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.adriabandiere.com\/de\/wp-json\/wp\/v2\/media\/54077"}],"wp:attachment":[{"href":"https:\/\/www.adriabandiere.com\/de\/wp-json\/wp\/v2\/media?parent=49985"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.adriabandiere.com\/de\/wp-json\/wp\/v2\/product_brand?post=49985"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.adriabandiere.com\/de\/wp-json\/wp\/v2\/product_cat?post=49985"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.adriabandiere.com\/de\/wp-json\/wp\/v2\/product_tag?post=49985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}