{"id":48276,"date":"2021-01-27T15:08:57","date_gmt":"2021-01-28T14:06:18","guid":{"rendered":"https:\/\/labs.giamaica.app\/webit\/adriabandiere.com\/shop\/unkategorisiert\/albanien\/"},"modified":"2021-01-28T15:06:18","modified_gmt":"2021-01-28T14:06:18","slug":"albanien","status":"publish","type":"product","link":"https:\/\/www.adriabandiere.com\/de\/prodotti\/flaggen\/auslandische-nationen\/albanien\/","title":{"rendered":"ALBANIEN"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Albanien, cm 100&#215;150 billiges Polyester<br \/>\n30b01al Albanien, Polyestertisch 14&#215;21 cm<br \/>\n32b024al Albanien, 20 x 30 cm<br \/>\n32b043al Albanien, 15,5 x 23 cm<br \/>\n64b057al Albanien, 100&#215;150 cm bestickter Twill<br \/>\nba021 Albanien, 20&#215;30 cm<br \/>\nba022 Albanien, 30&#215;45 cm<br \/>\nba023 Albanien, 40&#215;60 cm<br \/>\nba024 Albanien, 50&#215;75 cm<br \/>\nba024xpx Albanien, 60&#215;90 cm Seepolyester<br \/>\nba025 Albanien, 70&#215;100 cm<br \/>\nba026 Albanien, 80&#215;120 cm<br \/>\nba027 Albanien, 100 x 150 cm<br \/>\nba027px Albanien, cm 100&#215;150 nautisches Polyester<br \/>\nba028 Albanien, 130&#215;200 cm<br \/>\nba029 Albanien, 150 x 225 cm<br \/>\nba030 Albanien, 200&#215;300 cm<br \/>\nba030d Albanien, cm 200&#215;300 doppelt<br \/>\nba030px Albanien, cm 200&#215;300<\/p>\n","protected":false},"featured_media":41640,"template":"","meta":{"_acf_changed":false,"ngg_post_thumbnail":0},"product_brand":[],"product_cat":[478,456],"product_tag":[],"class_list":{"0":"post-48276","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-auslandische-nationen","7":"product_cat-flaggen","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.11 (Yoast SEO v20.11) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ALBANIEN - AdriaBandiere<\/title>\n<meta name=\"description\" content=\"Scopri ALBANIEN e gli altri prodotti del catalogo di AdriaBandiere. Entra nel sito.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.adriabandiere.com\/de\/prodotti\/flaggen\/auslandische-nationen\/albanien\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ALBANIEN\" \/>\n<meta property=\"og:description\" content=\"Scopri ALBANIEN e gli altri prodotti del catalogo di AdriaBandiere. Entra nel sito.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.adriabandiere.com\/de\/prodotti\/flaggen\/auslandische-nationen\/albanien\/\" \/>\n<meta property=\"og:site_name\" content=\"Adria Bandiere\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.adriabandiere.com\/wp-content\/uploads\/2021\/01\/100alb-6-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.adriabandiere.com\/de\/prodotti\/flaggen\/auslandische-nationen\/albanien\/\",\"url\":\"https:\/\/www.adriabandiere.com\/de\/prodotti\/flaggen\/auslandische-nationen\/albanien\/\",\"name\":\"ALBANIEN - AdriaBandiere\",\"isPartOf\":{\"@id\":\"https:\/\/www.adriabandiere.com\/de\/#website\"},\"datePublished\":\"2021-01-28T14:06:18+00:00\",\"dateModified\":\"2021-01-28T14:06:18+00:00\",\"description\":\"Scopri ALBANIEN e gli altri prodotti del catalogo di AdriaBandiere. Entra nel sito.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.adriabandiere.com\/de\/prodotti\/flaggen\/auslandische-nationen\/albanien\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.adriabandiere.com\/de\/prodotti\/flaggen\/auslandische-nationen\/albanien\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.adriabandiere.com\/de\/prodotti\/flaggen\/auslandische-nationen\/albanien\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prodotti\",\"item\":\"https:\/\/www.adriabandiere.com\/it\/prodotti\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ALBANIEN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.adriabandiere.com\/de\/#website\",\"url\":\"https:\/\/www.adriabandiere.com\/de\/\",\"name\":\"Adria Bandiere\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.adriabandiere.com\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ALBANIEN - AdriaBandiere","description":"Scopri ALBANIEN e gli altri prodotti del catalogo di AdriaBandiere. Entra nel sito.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.adriabandiere.com\/de\/prodotti\/flaggen\/auslandische-nationen\/albanien\/","og_locale":"de_DE","og_type":"article","og_title":"ALBANIEN","og_description":"Scopri ALBANIEN e gli altri prodotti del catalogo di AdriaBandiere. Entra nel sito.","og_url":"https:\/\/www.adriabandiere.com\/de\/prodotti\/flaggen\/auslandische-nationen\/albanien\/","og_site_name":"Adria Bandiere","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.adriabandiere.com\/wp-content\/uploads\/2021\/01\/100alb-6-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.adriabandiere.com\/de\/prodotti\/flaggen\/auslandische-nationen\/albanien\/","url":"https:\/\/www.adriabandiere.com\/de\/prodotti\/flaggen\/auslandische-nationen\/albanien\/","name":"ALBANIEN - AdriaBandiere","isPartOf":{"@id":"https:\/\/www.adriabandiere.com\/de\/#website"},"datePublished":"2021-01-28T14:06:18+00:00","dateModified":"2021-01-28T14:06:18+00:00","description":"Scopri ALBANIEN e gli altri prodotti del catalogo di AdriaBandiere. Entra nel sito.","breadcrumb":{"@id":"https:\/\/www.adriabandiere.com\/de\/prodotti\/flaggen\/auslandische-nationen\/albanien\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.adriabandiere.com\/de\/prodotti\/flaggen\/auslandische-nationen\/albanien\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.adriabandiere.com\/de\/prodotti\/flaggen\/auslandische-nationen\/albanien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prodotti","item":"https:\/\/www.adriabandiere.com\/it\/prodotti\/"},{"@type":"ListItem","position":2,"name":"ALBANIEN"}]},{"@type":"WebSite","@id":"https:\/\/www.adriabandiere.com\/de\/#website","url":"https:\/\/www.adriabandiere.com\/de\/","name":"Adria Bandiere","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.adriabandiere.com\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.adriabandiere.com\/de\/wp-json\/wp\/v2\/product\/48276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.adriabandiere.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.adriabandiere.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.adriabandiere.com\/de\/wp-json\/wp\/v2\/media\/41640"}],"wp:attachment":[{"href":"https:\/\/www.adriabandiere.com\/de\/wp-json\/wp\/v2\/media?parent=48276"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.adriabandiere.com\/de\/wp-json\/wp\/v2\/product_brand?post=48276"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.adriabandiere.com\/de\/wp-json\/wp\/v2\/product_cat?post=48276"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.adriabandiere.com\/de\/wp-json\/wp\/v2\/product_tag?post=48276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}